{"id":213947,"date":"2016-09-10T01:55:09","date_gmt":"2016-09-09T23:55:09","guid":{"rendered":"http:\/\/www.mainstyle.org\/wp-content\/uploads\/Graffiti_best_of_RTSWGKRSL_August_2016-49.jpg"},"modified":"2016-09-10T01:55:09","modified_gmt":"2016-09-09T23:55:09","slug":"graffiti_best_of_rtswgkrsl_august_2016-49","status":"inherit","type":"attachment","link":"https:\/\/mainstyle.org\/index.php\/2016\/09\/10\/graffiti-vom-frankfurt-ratswegkreisel-hall-of-fame-best-of-august-2016\/graffiti_best_of_rtswgkrsl_august_2016-49\/","title":{"rendered":"graffiti_best_of_rtswgkrsl_august_2016-49"},"author":360,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":[],"class_list":["post-213947","attachment","type-attachment","status-inherit","hentry"],"jetpack_shortlink":"https:\/\/wp.me\/a4RzNO-TEL","jetpack_likes_enabled":true,"jetpack_sharing_enabled":true,"description":{"rendered":"<p class=\"attachment\"><a href=\"https:\/\/i0.wp.com\/mainstyle.org\/wp-content\/uploads\/Graffiti_best_of_RTSWGKRSL_August_2016-49.jpg?ssl=1\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/i0.wp.com\/mainstyle.org\/wp-content\/uploads\/Graffiti_best_of_RTSWGKRSL_August_2016-49.jpg?fit=300%2C200&amp;ssl=1\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/i0.wp.com\/mainstyle.org\/wp-content\/uploads\/Graffiti_best_of_RTSWGKRSL_August_2016-49.jpg?w=1024&amp;ssl=1 1024w, https:\/\/i0.wp.com\/mainstyle.org\/wp-content\/uploads\/Graffiti_best_of_RTSWGKRSL_August_2016-49.jpg?resize=300%2C200&amp;ssl=1 300w, https:\/\/i0.wp.com\/mainstyle.org\/wp-content\/uploads\/Graffiti_best_of_RTSWGKRSL_August_2016-49.jpg?resize=768%2C511&amp;ssl=1 768w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" data-attachment-id=\"213947\" data-permalink=\"https:\/\/mainstyle.org\/index.php\/2016\/09\/10\/graffiti-vom-frankfurt-ratswegkreisel-hall-of-fame-best-of-august-2016\/graffiti_best_of_rtswgkrsl_august_2016-49\/\" data-orig-file=\"https:\/\/i0.wp.com\/mainstyle.org\/wp-content\/uploads\/Graffiti_best_of_RTSWGKRSL_August_2016-49.jpg?fit=1024%2C681&amp;ssl=1\" data-orig-size=\"1024,681\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;M9 Digital Camera&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;1471020777&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;35&quot;,&quot;iso&quot;:&quot;160&quot;,&quot;shutter_speed&quot;:&quot;0.0013333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"graffiti_best_of_rtswgkrsl_august_2016-49\" data-image-description=\"\" data-image-caption=\"\" data-large-file=\"https:\/\/i0.wp.com\/mainstyle.org\/wp-content\/uploads\/Graffiti_best_of_RTSWGKRSL_August_2016-49.jpg?fit=584%2C388&amp;ssl=1\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":1024,"height":681,"file":"Graffiti_best_of_RTSWGKRSL_August_2016-49.jpg","sizes":{"thumbnail":{"file":"Graffiti_best_of_RTSWGKRSL_August_2016-49-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/mainstyle.org\/wp-content\/uploads\/Graffiti_best_of_RTSWGKRSL_August_2016-49.jpg?resize=150%2C150&ssl=1"},"medium":{"file":"Graffiti_best_of_RTSWGKRSL_August_2016-49-300x200.jpg","width":300,"height":200,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/mainstyle.org\/wp-content\/uploads\/Graffiti_best_of_RTSWGKRSL_August_2016-49.jpg?fit=300%2C200&ssl=1"},"medium_large":{"file":"Graffiti_best_of_RTSWGKRSL_August_2016-49-768x511.jpg","width":768,"height":511,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/mainstyle.org\/wp-content\/uploads\/Graffiti_best_of_RTSWGKRSL_August_2016-49.jpg?fit=584%2C389&ssl=1"},"large":{"file":"Graffiti_best_of_RTSWGKRSL_August_2016-49-1024x681.jpg","width":1024,"height":681,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/mainstyle.org\/wp-content\/uploads\/Graffiti_best_of_RTSWGKRSL_August_2016-49.jpg?fit=584%2C388&ssl=1"},"post-thumbnail":{"file":"Graffiti_best_of_RTSWGKRSL_August_2016-49-940x198.jpg","width":940,"height":198,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/mainstyle.org\/wp-content\/uploads\/Graffiti_best_of_RTSWGKRSL_August_2016-49.jpg?resize=940%2C198&ssl=1"},"full":{"file":"Graffiti_best_of_RTSWGKRSL_August_2016-49.jpg?fit=1024%2C681&ssl=1","width":1024,"height":681,"mime_type":"image\/jpeg","source_url":"https:\/\/i0.wp.com\/mainstyle.org\/wp-content\/uploads\/Graffiti_best_of_RTSWGKRSL_August_2016-49.jpg?fit=1024%2C681&ssl=1"}},"image_meta":{"aperture":"4.8","credit":"","camera":"M9 Digital Camera","caption":"","created_timestamp":"1471020777","copyright":"","focal_length":"35","iso":"160","shutter_speed":"0.0013333333333333","title":"","orientation":"0","keywords":[]}},"post":213838,"source_url":"https:\/\/mainstyle.org\/wp-content\/uploads\/Graffiti_best_of_RTSWGKRSL_August_2016-49.jpg","_links":{"self":[{"href":"https:\/\/mainstyle.org\/index.php\/wp-json\/wp\/v2\/media\/213947","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mainstyle.org\/index.php\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/mainstyle.org\/index.php\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/mainstyle.org\/index.php\/wp-json\/wp\/v2\/users\/360"}],"replies":[{"embeddable":true,"href":"https:\/\/mainstyle.org\/index.php\/wp-json\/wp\/v2\/comments?post=213947"}],"wp:attached-to":[{"embeddable":true,"post_type":"post","id":213838,"href":"https:\/\/mainstyle.org\/index.php\/wp-json\/wp\/v2\/posts\/213838"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}